{"id":3921,"date":"2018-10-03T11:28:56","date_gmt":"2018-10-09T11:31:57","guid":{"rendered":"http:\/\/metalowiec.dev.netk.pl\/?post_type=product&#038;p=3921"},"modified":"2018-10-12T10:49:51","modified_gmt":"2018-10-12T08:49:51","slug":"pflegewagen","status":"publish","type":"product","link":"https:\/\/metalowiec.com.pl\/de\/produkt\/pflegewagen\/","title":{"rendered":"Pflegewagen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row gap=&#8220;20&#8243; el_class=&#8220;m-b-md&#8220;][vc_column width=&#8220;2\/3&#8243;][vc_custom_heading text=&#8220;Beschreibung&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_column_text]<\/p>\n<ul>\n<li><span lang=\"de-DE\">Ablageboden aus Stahlblech, pulverbeschichtet oder Edelstahl<\/span><\/li>\n<li><span lang=\"de-DE\">Schalen aus Kunststoff<\/span><\/li>\n<li><span lang=\"de-DE\">Sch\u00fcssel aus Edelstahl<\/span><\/li>\n<li><span lang=\"de-DE\">Abfallsackhalter mit Abdeckung<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_custom_heading text=&#8220;Technische Daten&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_column_text]<\/p>\n<ul>\n<li><span lang=\"de-DE\">L\u00e4nge 756mm \u00b15mm<\/span><\/li>\n<li><span lang=\"de-DE\">Breite 454mm \u00b15mm<\/span><\/li>\n<li><span lang=\"de-DE\">H\u00f6he 755mm \u00b15mm<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8220;Farbe&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_column_text]<\/p>\n<ul class=\"variants-list\">\n<li class=\"color-tile\">Metallfarben<\/li>\n<li class=\"ral ral-7035\">RAL 7035<\/li>\n<li class=\"ral ral-9006\">RAL 9006<\/li>\n<li class=\"ral ral-9007\">RAL 9007<\/li>\n<li class=\"ral ral-1015\">RAL 1015<\/li>\n<li class=\"ral ral-5024\">RAL 5024<\/li>\n<li class=\"ral ral-9005\">RAL 9005<\/li>\n<li class=\"ral ral-9016\">RAL 9016<\/li>\n<li class=\"ral ral-6018\">RAL 6018<\/li>\n<li class=\"ral RAL-1003\">RAL 1003<\/li>\n<li class=\"ral RAL-3002\">RAL 3002<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><span lang=\"de-DE\">Rahmen aus Stahlprofilen, pulverbeschichtet<\/span><\/p>\n<p><span lang=\"de-DE\">M\u00f6gliche Ausstattung<\/span><\/p>\n","protected":false},"featured_media":3139,"template":"","meta":[],"product_brand":[],"product_cat":[194,192],"product_tag":[],"class_list":{"0":"post-3921","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-andere-de","7":"product_cat-krankenhausausrustung","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/metalowiec.com.pl\/de\/wp-json\/wp\/v2\/product\/3921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metalowiec.com.pl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/metalowiec.com.pl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metalowiec.com.pl\/de\/wp-json\/wp\/v2\/media\/3139"}],"wp:attachment":[{"href":"https:\/\/metalowiec.com.pl\/de\/wp-json\/wp\/v2\/media?parent=3921"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/metalowiec.com.pl\/de\/wp-json\/wp\/v2\/product_brand?post=3921"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/metalowiec.com.pl\/de\/wp-json\/wp\/v2\/product_cat?post=3921"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/metalowiec.com.pl\/de\/wp-json\/wp\/v2\/product_tag?post=3921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}